{"id":11504,"date":"2024-05-20T21:13:29","date_gmt":"2024-05-20T19:13:29","guid":{"rendered":"https:\/\/kettiricordi.com\/portfolio\/amiee-jamie-es-eng\/"},"modified":"2026-05-09T18:20:59","modified_gmt":"2026-05-09T16:20:59","slug":"aashna-arjun","status":"publish","type":"portfolios","link":"https:\/\/kettiricordi.com\/es\/portfolio\/aashna-arjun\/","title":{"rendered":"Aashna y Arjun"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11504\" class=\"elementor elementor-11504\" data-elementor-post-type=\"portfolios\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50d1bd2c e-flex e-con-boxed e-con e-parent\" data-id=\"50d1bd2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e824a71 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5e824a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-664386b5 e-flex e-con-boxed e-con e-parent\" data-id=\"664386b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-512aee80 animated-slow elementor-invisible elementor-widget elementor-widget-artale-animated-text\" data-id=\"512aee80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<h1>\n\t\tAASHNA & ARJUN\t<\/h1>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48fbd048 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48fbd048\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1957bd8\" data-id=\"1957bd8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44ae0f04 elementor-widget elementor-widget-artale-animated-text\" data-id=\"44ae0f04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<span>\n\t\tA large, festive and colorful indian wedding in lloret del mar, girona \t<\/span>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-616802c2 animated-slow elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"616802c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A wedding that exuded charm and traditional culture &#8211; it was a ceremony rich in symbolism, vibrant colours and abundance in each of its rituals before, during, and at the moment of the union.<br><span style=\"font-family: inherit; font-weight: inherit;\"><i><br>Shot with Nikhil Shastri &amp; Andrzej Witek.<\/i><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17fc5ecf elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"17fc5ecf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-432ba8b0\" data-id=\"432ba8b0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1467e97 elementor-widget elementor-widget-artale-gallery-horizontal\" data-id=\"1467e97\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-gallery-horizontal.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"horizontal-gallery-1467e97\" class=\"horizontal-gallery-wrapper\" data-autoplay=\"3000\" data-loop=\"1\" data-navigation=\"0\" data-pagination=\"0\" data-parallax=\"0\" data-fullscreen=\"0\">\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"horizontal-gallery-cell\" style=\"margin-right:10px\">\n\t\t\t\t\t\t<img class=\"horizontal-gallery-cell-img\" data-flickity-lazyload=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-768x512.jpg\" alt=\"\" style=\"height:350px;\" \/>\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-404133e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"404133e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32c73aeb\" data-id=\"32c73aeb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6524b560 elementor-widget__width-inherit elementor-widget elementor-widget-artale-animated-text\" data-id=\"6524b560\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<div>\n\t\tFull gallery below \t<\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3857707 elementor-widget__width-auto elementor-widget-divider--view-line elementor-widget elementor-widget-global elementor-global-17917 elementor-widget-divider\" data-id=\"3857707\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_is_smoove&quot;:&quot;true&quot;,&quot;artale_ext_smoove_duration&quot;:800,&quot;artale_ext_smoove_scalex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_scaley&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_smoove_disable&quot;:1,&quot;artale_ext_smoove_rotatex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_rotatey&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_rotatez&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatey&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatez&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_skewx&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_skewy&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_perspective&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1000,&quot;sizes&quot;:[]},&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6652fdab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6652fdab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42ea13ca\" data-id=\"42ea13ca\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;artale_ext_is_sticky&quot;:&quot;true&quot;,&quot;artale_ext_sticky_top_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:120,&quot;sizes&quot;:[]},&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c645a84 animated-slow elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-artale-animated-text\" data-id=\"7c645a84\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-left transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<h1>\n\t\tAashna & Arjun\t<\/h1>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee3475d animated-slow elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-artale-animated-text\" data-id=\"7ee3475d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-left transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"400\" data-transition-duration=\"800\">\n\t\t<span>\n\t\t06 May, 2022\t<\/span>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a24d139 elementor-widget-mobile__width-initial elementor-widget elementor-widget-wp-widget-media_audio\" data-id=\"4a24d139\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"wp-widget-media_audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-11504-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2026\/05\/Suraj-Nepal-Wind-and-Grass.mp3?_=1\" \/><source type=\"audio\/mpeg\" src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2026\/05\/Suraj-Nepal-Wind-and-Grass.mp3?_=1\" \/><a href=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2026\/05\/Suraj-Nepal-Wind-and-Grass.mp3\">https:\/\/kettiricordi.com\/wp-content\/uploads\/2026\/05\/Suraj-Nepal-Wind-and-Grass.mp3<\/a><\/audio>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d859202 animated-slow elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2d859202\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>ENG<\/strong><\/p><p>It was my first time at a traditional Hindu wedding, which I was part of by assisting with the photographic registry, along with my colleagues and friends, <a href=\"https:\/\/www.nikhilshastri.com\/\">Nikhil<\/a> and <a href=\"https:\/\/witekphotography.com\/\">Andrjez<\/a>, in the spring of 2022. The ceremony took place within the premises of the S&#8217;Agar\u00f3 Hotel in a celebration that lasted three days. It is worth noting that traditional Indian weddings, apart from being extraordinary, are characterised by their rich ceremonial richness full of symbolism, vibrant colours and abundance in each of their rituals before, during and at the moment of the union.<\/p><p>In this case, the wedding of Aashna and Arjun stood out in large part because of the large number of family members summoned in a country outside the country of their birth, considering the thousands of kilometres of distance between Spain and India, as well as the great variety of guests from different parts of the world, including friends and people close to the couple.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cee991 animated-slow elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1cee991\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>It was a ceremony that had everything from the very beginning, with no detail overlooked. From the Sangeet feast, where the women of both families gather to beautify and prepare the future bride through the Mehndi technique, to the groom&#8217;s preparations in a rite similar to the Sangeet, although on this occasion his body is smeared with turmeric, and finally, the wedding ceremony with the three essential rites; the Homa ritual with offerings to the fire; the Panigrahena which indicates the bond of union of the bride and groom; and the Satapadi ritual where the bride and groom walk seven times around the sacred fire, between chanting mantras and reading sacred texts to invoke blessings on the union of the couple.<\/p><p>A wedding that did not go unnoticed and that exuded charm and traditional culture during the days we were part of. This magnificent celebration remains in my memory, an event that was unique and that I was able to be part of to celebrate the love that comes from India.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-622657a animated-slow elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"622657a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<hr \/><p><strong>ES<\/strong><\/p><p>Fue mi primera vez en una boda tradicional hind\u00fa, en la que fui parte asistiendo con el registro fotogr\u00e1fico, junto a mis colegas y amigos, <a href=\"https:\/\/www.nikhilshastri.com\/\">Nikhil <\/a>and <a href=\"https:\/\/witekphotography.com\/\">Andrjez<\/a>, en la primavera del 2022. La ceremonia tuvo lugar dentro de las instalaciones del Hotel S\u2019Agar\u00f3 en una celebraci\u00f3n que dur\u00f3 tres d\u00edas. Cabe resaltar que las bodas tradicionales de la India, adem\u00e1s de ser extraordinarias, se caracterizan por la gran riqueza ceremonial cargada de simbolismos, colores vibrantes y mucha abundancia en cada uno de sus rituales antes, durante y al momento de la uni\u00f3n.<\/p><p>En este caso, la boda de Aashna y Arjun se destac\u00f3 en gran parte por el gran n\u00famero de familiares convocados en un pa\u00eds ajeno al pa\u00eds natal, considerando los miles de kil\u00f3metros de distancia entre Espa\u00f1a y la India, como tambi\u00e9n, tuvo lugar la gran variedad de invitados de distintas partes del mundo, entre amigos y personas allegadas a la pareja.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16182c5c animated-slow elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"16182c5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una ceremonia que tuvo de todo desde el primer momento sin dejar pasar por alto ning\u00fan detalle. Desde la fiesta del Sangeet, en donde las mujeres de ambas familias se re\u00fanen para embellecer y preparar a la futura esposa mediante la t\u00e9cnica del Mehndi, pasando por los preparativos del novio en medio de un rito similar al del Sangeet, aunque en esta ocasi\u00f3n se embadurna el cuerpo de \u00e9l con c\u00farcuma, y, finalmente, la ceremonia nupcial con los tres ritos esenciales; el ritual de Homa con ofrendas al fuego; el Panigrahena que indica el v\u00ednculo de uni\u00f3n de los novios; y el ritual Satapadi donde los novios dan siete vueltas alrededor del fuego sagrado, entre cantos de mantras y lecturas de textos sagrados para invocar las bendiciones a la uni\u00f3n de la pareja.<\/p><p>Una boda que no pas\u00f3 desapercibida y que destil\u00f3 encanto y cultura tradicional durante los d\u00edas que fuimos parte. Queda en mi memoria esta magnifica celebraci\u00f3n, un acontecimiento que fue \u00fanico y del que pude formar parte para celebrar el amor proveniente de la India.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c2b83cc elementor-widget__width-auto animated-slow elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-artale-animated-text\" data-id=\"6c2b83cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:800,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-left transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"800\" data-transition-duration=\"800\">\n\t\t<div>\n\t\tWedding\t<\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d47bbb9\" data-id=\"1d47bbb9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2597f24e elementor-widget elementor-widget-image\" data-id=\"2597f24e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-1024x683.jpg\" class=\"attachment-large size-large wp-image-10723\" alt=\"\" srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_24-330x220.jpg 330w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7780a481 elementor-widget elementor-widget-image\" data-id=\"7780a481\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-1024x683.jpg\" class=\"attachment-large size-large wp-image-10700 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_01-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c193b0c elementor-widget elementor-widget-image\" data-id=\"4c193b0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-1024x683.jpg\" class=\"attachment-large size-large wp-image-10701 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_02-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a9fae92 elementor-widget elementor-widget-image\" data-id=\"1a9fae92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-1024x683.jpg\" class=\"attachment-large size-large wp-image-10702 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_03-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f3cb2df elementor-widget elementor-widget-image\" data-id=\"4f3cb2df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-1024x683.jpg\" class=\"attachment-large size-large wp-image-10704 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_05-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4576b899 elementor-widget elementor-widget-image\" data-id=\"4576b899\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-1024x683.jpg\" class=\"attachment-large size-large wp-image-10703 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_04-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d87e287 elementor-widget elementor-widget-image\" data-id=\"d87e287\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-1024x683.jpg\" class=\"attachment-large size-large wp-image-10705 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_06-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49afc79c elementor-widget elementor-widget-image\" data-id=\"49afc79c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-1024x683.jpg\" class=\"attachment-large size-large wp-image-10708 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_09-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32577325 elementor-widget elementor-widget-image\" data-id=\"32577325\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-1024x683.jpg\" class=\"attachment-large size-large wp-image-10707 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_08-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-308dcf07 elementor-widget elementor-widget-image\" data-id=\"308dcf07\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-1024x683.jpg\" class=\"attachment-large size-large wp-image-10709 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_10-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54c918bf elementor-widget elementor-widget-image\" data-id=\"54c918bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-1024x683.jpg\" class=\"attachment-large size-large wp-image-10710 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_11-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c736d7c elementor-widget elementor-widget-image\" data-id=\"3c736d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-1024x683.jpg\" class=\"attachment-large size-large wp-image-10711 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_12-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-339d03ee elementor-widget elementor-widget-image\" data-id=\"339d03ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-1024x683.jpg\" class=\"attachment-large size-large wp-image-10720 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_21-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77936f77 elementor-widget elementor-widget-image\" data-id=\"77936f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-1024x683.jpg\" class=\"attachment-large size-large wp-image-10713 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_14-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1689bff4 elementor-widget elementor-widget-image\" data-id=\"1689bff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-1024x683.jpg\" class=\"attachment-large size-large wp-image-10718 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_19-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589aa24f elementor-widget elementor-widget-image\" data-id=\"589aa24f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-1024x683.jpg\" class=\"attachment-large size-large wp-image-10724 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_25-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a5231a elementor-widget elementor-widget-image\" data-id=\"57a5231a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-1024x683.jpg\" class=\"attachment-large size-large wp-image-10721 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_22-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c73ee6 elementor-widget elementor-widget-image\" data-id=\"63c73ee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-1024x683.jpg\" class=\"attachment-large size-large wp-image-10725 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_26-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15f24923 elementor-widget elementor-widget-image\" data-id=\"15f24923\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-1024x683.jpg\" class=\"attachment-large size-large wp-image-10726 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_27-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cb93de7 elementor-widget elementor-widget-image\" data-id=\"7cb93de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-1024x683.jpg\" class=\"attachment-large size-large wp-image-10728 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_29-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5064793e elementor-widget elementor-widget-image\" data-id=\"5064793e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-1024x683.jpg\" class=\"attachment-large size-large wp-image-10727 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_28-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20b9683 elementor-widget elementor-widget-image\" data-id=\"20b9683\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-1024x683.jpg\" class=\"attachment-large size-large wp-image-10729 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_30-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76b63d8a elementor-widget elementor-widget-image\" data-id=\"76b63d8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-1024x683.jpg\" class=\"attachment-large size-large wp-image-10730 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_31-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1002596a elementor-widget elementor-widget-image\" data-id=\"1002596a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-1024x683.jpg\" class=\"attachment-large size-large wp-image-10750 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_51-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6998a04c elementor-widget elementor-widget-image\" data-id=\"6998a04c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-1024x683.jpg\" class=\"attachment-large size-large wp-image-10751 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_52-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a76ce0 elementor-widget elementor-widget-image\" data-id=\"1a76ce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-1024x683.jpg\" class=\"attachment-large size-large wp-image-10749 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_50-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739e3705 elementor-widget elementor-widget-image\" data-id=\"739e3705\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-1024x683.jpg\" class=\"attachment-large size-large wp-image-10732 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_33-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-624a456e elementor-widget elementor-widget-image\" data-id=\"624a456e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-1024x683.jpg\" class=\"attachment-large size-large wp-image-10733 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_34-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94c11d elementor-widget elementor-widget-image\" data-id=\"1d94c11d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-1024x683.jpg\" class=\"attachment-large size-large wp-image-10734 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_35-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc9fce0 elementor-widget elementor-widget-image\" data-id=\"cc9fce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-1024x683.jpg\" class=\"attachment-large size-large wp-image-10735 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_36-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64515793 elementor-widget elementor-widget-image\" data-id=\"64515793\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-1024x683.jpg\" class=\"attachment-large size-large wp-image-10736 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_37-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d31f3f7 elementor-widget elementor-widget-image\" data-id=\"4d31f3f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-1024x683.jpg\" class=\"attachment-large size-large wp-image-10737 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_38-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aeeec5 elementor-widget elementor-widget-image\" data-id=\"1aeeec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-1024x683.jpg\" class=\"attachment-large size-large wp-image-10738 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_39-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142b90a elementor-widget elementor-widget-image\" data-id=\"142b90a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-1024x683.jpg\" class=\"attachment-large size-large wp-image-10740 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_41-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50d22fcc elementor-widget elementor-widget-image\" data-id=\"50d22fcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-1024x683.jpg\" class=\"attachment-large size-large wp-image-10741 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_42-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aa028a1 elementor-widget elementor-widget-image\" data-id=\"4aa028a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-1024x683.jpg\" class=\"attachment-large size-large wp-image-10742 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_43-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52f636a elementor-widget elementor-widget-image\" data-id=\"52f636a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-1024x683.jpg\" class=\"attachment-large size-large wp-image-10743 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_44-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3ae7f7 elementor-widget elementor-widget-image\" data-id=\"3e3ae7f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-1024x683.jpg\" class=\"attachment-large size-large wp-image-10744 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_45-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e7f24 elementor-widget elementor-widget-image\" data-id=\"35e7f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-1024x683.jpg\" class=\"attachment-large size-large wp-image-10745 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_46-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1ce5c3 elementor-widget elementor-widget-image\" data-id=\"d1ce5c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-1024x683.jpg\" class=\"attachment-large size-large wp-image-10746 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_47-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b006fcd elementor-widget elementor-widget-image\" data-id=\"5b006fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-1024x683.jpg\" class=\"attachment-large size-large wp-image-10748 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_49-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7b2d79 elementor-widget elementor-widget-image\" data-id=\"3e7b2d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-1024x683.jpg\" class=\"attachment-large size-large wp-image-10754 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_55-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3048b716 elementor-widget elementor-widget-image\" data-id=\"3048b716\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-1024x683.jpg\" class=\"attachment-large size-large wp-image-10753 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_54-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c874464 elementor-widget elementor-widget-image\" data-id=\"c874464\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-1024x683.jpg\" class=\"attachment-large size-large wp-image-10752 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_53-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e8f648 elementor-widget elementor-widget-image\" data-id=\"2e8f648\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-1024x683.jpg\" class=\"attachment-large size-large wp-image-10755 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_56-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d77d0 elementor-widget elementor-widget-image\" data-id=\"31d77d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-1024x683.jpg\" class=\"attachment-large size-large wp-image-10756 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_58-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c6096 elementor-widget elementor-widget-image\" data-id=\"f6c6096\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-1024x683.jpg\" class=\"attachment-large size-large wp-image-10757 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_59-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33333a8 elementor-widget elementor-widget-image\" data-id=\"33333a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-1024x683.jpg\" class=\"attachment-large size-large wp-image-10758 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_60-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3fb133 elementor-widget elementor-widget-image\" data-id=\"f3fb133\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-1024x683.jpg\" class=\"attachment-large size-large wp-image-10759 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_61-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeccd3e elementor-widget elementor-widget-image\" data-id=\"aeccd3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-1024x683.jpg\" class=\"attachment-large size-large wp-image-10760 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_62-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782d428 elementor-widget elementor-widget-image\" data-id=\"782d428\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-1024x683.jpg\" class=\"attachment-large size-large wp-image-10761 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_63-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a74ba0 elementor-widget elementor-widget-image\" data-id=\"7a74ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-1024x683.jpg\" class=\"attachment-large size-large wp-image-10762 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_64-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62bd22b elementor-widget elementor-widget-image\" data-id=\"62bd22b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-1024x683.jpg\" class=\"attachment-large size-large wp-image-10763 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_65-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51936d6 elementor-widget elementor-widget-image\" data-id=\"51936d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-1024x683.jpg\" class=\"attachment-large size-large wp-image-10771 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_73-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec7504c elementor-widget elementor-widget-image\" data-id=\"ec7504c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-1024x683.jpg\" class=\"attachment-large size-large wp-image-10722 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_23-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85c8af9 elementor-widget elementor-widget-image\" data-id=\"85c8af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"732\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-1024x732.jpg\" class=\"attachment-large size-large wp-image-10765 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-1024x732.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-300x214.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-768x549.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-1536x1097.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-2048x1463.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-440x314.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-600x429.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_67-308x220.jpg 308w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/732;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b457f9f elementor-widget elementor-widget-image\" data-id=\"b457f9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-1024x683.jpg\" class=\"attachment-large size-large wp-image-10767 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_69-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a2807 elementor-widget elementor-widget-image\" data-id=\"c9a2807\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-1024x683.jpg\" class=\"attachment-large size-large wp-image-10768 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_70-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0618894 elementor-widget elementor-widget-image\" data-id=\"0618894\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-1024x683.jpg\" class=\"attachment-large size-large wp-image-10770 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dfd367 elementor-widget elementor-widget-image\" data-id=\"0dfd367\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-1024x683.jpg\" class=\"attachment-large size-large wp-image-10773 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_75-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c8a0e elementor-widget elementor-widget-image\" data-id=\"69c8a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-1024x683.jpg\" class=\"attachment-large size-large wp-image-10772 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_74-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-766e58c elementor-widget elementor-widget-image\" data-id=\"766e58c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-1024x683.jpg\" class=\"attachment-large size-large wp-image-10774 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_76-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-336f603 elementor-widget elementor-widget-image\" data-id=\"336f603\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-1024x683.jpg\" class=\"attachment-large size-large wp-image-10776 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_78-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4e23d0 elementor-widget elementor-widget-image\" data-id=\"e4e23d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-1024x683.jpg\" class=\"attachment-large size-large wp-image-10775 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_77-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfee02c elementor-widget elementor-widget-image\" data-id=\"cfee02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-1024x683.jpg\" class=\"attachment-large size-large wp-image-10780 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_82-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ceb62 elementor-widget elementor-widget-image\" data-id=\"31ceb62\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-1024x683.jpg\" class=\"attachment-large size-large wp-image-10781 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_83-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b061bbd elementor-widget elementor-widget-image\" data-id=\"b061bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-1024x683.jpg\" class=\"attachment-large size-large wp-image-10779 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_81-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c0b7d9 elementor-widget elementor-widget-image\" data-id=\"5c0b7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-1024x683.jpg\" class=\"attachment-large size-large wp-image-10777 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_79-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-188e15c elementor-widget elementor-widget-image\" data-id=\"188e15c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-1024x683.jpg\" class=\"attachment-large size-large wp-image-10778 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_80-330x220.jpg 330w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" data-original-sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a181287 elementor-widget elementor-widget-image\" data-id=\"a181287\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_image_is_animation&quot;:&quot;false&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-683x1024.jpg\" class=\"attachment-large size-large wp-image-10782 lazyload\" alt=\"\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-683x1024.jpg 683w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-200x300.jpg 200w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-768x1152.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-1024x1536.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-1366x2048.jpg 1366w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-440x660.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-600x900.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84-147x220.jpg 147w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_84.jpg 1667w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 683px; --smush-placeholder-aspect-ratio: 683\/1024;\" data-original-sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a47e618 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a47e618\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-639ee20d\" data-id=\"639ee20d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-506b6293 elementor-widget__width-auto elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"506b6293\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_is_smoove&quot;:&quot;true&quot;,&quot;artale_ext_smoove_duration&quot;:800,&quot;artale_ext_smoove_scalex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_scaley&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_smoove_disable&quot;:1,&quot;artale_ext_smoove_rotatex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_rotatey&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_rotatez&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatey&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatez&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_skewx&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_skewy&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_perspective&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1000,&quot;sizes&quot;:[]},&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64477c54 elementor-widget__width-inherit elementor-widget elementor-widget-artale-animated-text\" data-id=\"64477c54\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<div>\n\t\tStories\t<\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25e5e999 elementor-section-full_width elementor-section-stretched animated-slow elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"25e5e999\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400,&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-610b9cad\" data-id=\"610b9cad\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2335cee7 elementor-widget elementor-widget-artale-portfolio-carousel\" data-id=\"2335cee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-portfolio-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"portfolio-carousel-wrapper\">\n\t<div class=\"owl-carousel\" data-pagination=\"0\" data-autoplay=\"1\" data-timer=\"8000\" data-items=\"2\" data-stage-padding=\"40\" data-margin=\"60\">\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/03\/AmieeJamie_Story_KR-46-700x466.jpg\" alt=\"\" width=\"700\" class=\"smush-dimensions lazyload\" style=\"--smush-image-width: 700px; --smush-image-aspect-ratio: 700\/466;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Amiee &amp; Jamie<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Wedding in Tarragona, Spain<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kettiricordi.com\/es\/portfolio\/amiee-jamie\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/NadineMarc_61-1-700x466.jpg\" alt=\"Martin_Ksenia_Cover image wedding photography\" width=\"700\" class=\"smush-dimensions lazyload\" style=\"--smush-image-width: 700px; --smush-image-aspect-ratio: 700\/466;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Ksenia &amp; Martin<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Wedding in Tarragona, Spain<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kettiricordi.com\/es\/portfolio\/martin-ksenia\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-700x466.jpg\" alt=\"\" width=\"700\" class=\"smush-dimensions lazyload\" style=\"--smush-image-width: 700px; --smush-image-aspect-ratio: 700\/466;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-srcset=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-700x466.jpg 700w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-300x200.jpg 300w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-1024x683.jpg 1024w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-768x512.jpg 768w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-1536x1024.jpg 1536w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-2048x1366.jpg 2048w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-440x293.jpg 440w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-600x400.jpg 600w, https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/04\/RosieJohn-74-330x220.jpg 330w\" data-sizes=\"auto\" data-original-sizes=\"(max-width: 700px) 100vw, 700px\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Rosie &amp; John<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Wedding in Barcelona, Spain<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kettiricordi.com\/es\/portfolio\/rosie-john\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/NadineMarc_51-700x466.jpg\" alt=\"\" width=\"700\" class=\"smush-dimensions lazyload\" style=\"--smush-image-width: 700px; --smush-image-aspect-ratio: 700\/466;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Nadine &amp; Marc<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Wedding in Girona, Spain<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/kettiricordi.com\/es\/portfolio\/nadine-marc\/\"  ><\/a>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-261cbd41 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"261cbd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_link_closed_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/kettiricordi.com\/services\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VIEW SERVICES<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Boda en Girona, Espa\u00f1a<\/p>","protected":false},"featured_media":10770,"comment_status":"closed","ping_status":"closed","template":"","portfolio_cat":[57,56,32,60],"class_list":["post-11504","portfolios","type-portfolios","status-publish","has-post-thumbnail","hentry","portfolio_cat-boda","portfolio_cat-es","portfolio_cat-grid","portfolio_cat-story-carousel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aashna &amp; Arjun - Kettiricordi | Aesthetic Documentary Wedding Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kettiricordi.com\/es\/portfolio\/aashna-arjun\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aashna &amp; Arjun - Kettiricordi | Aesthetic Documentary Wedding Photography\" \/>\n<meta property=\"og:description\" content=\"Wedding in Girona, Spain\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kettiricordi.com\/es\/portfolio\/aashna-arjun\/\" \/>\n<meta property=\"og:site_name\" content=\"Kettiricordi | Aesthetic Documentary Wedding Photography\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T16:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/\",\"url\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/\",\"name\":\"Aashna &amp; Arjun - Kettiricordi | Aesthetic Documentary Wedding Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kettiricordi.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AashnaArjun_72.jpg\",\"datePublished\":\"2024-05-20T19:13:29+00:00\",\"dateModified\":\"2026-05-09T16:20:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kettiricordi.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AashnaArjun_72.jpg\",\"contentUrl\":\"https:\\\/\\\/kettiricordi.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AashnaArjun_72.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/portfolio\\\/aashna-arjun\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kettiricordi.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aashna &amp; Arjun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/#website\",\"url\":\"https:\\\/\\\/kettiricordi.com\\\/\",\"name\":\"Kettiricordi | Aesthetic Documentary Wedding Photography\",\"description\":\"Wedding Photographer Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kettiricordi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/#organization\",\"name\":\"Kettiricordi | Aesthetic Documentary Wedding Photography\",\"url\":\"https:\\\/\\\/kettiricordi.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kettiricordi.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/KTR_Black.svg\",\"contentUrl\":\"https:\\\/\\\/kettiricordi.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/KTR_Black.svg\",\"width\":256,\"height\":142,\"caption\":\"Kettiricordi | Aesthetic Documentary Wedding Photography\"},\"image\":{\"@id\":\"https:\\\/\\\/kettiricordi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aashna &amp; Arjun - Kettiricordi | Aesthetic Documentary Wedding Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kettiricordi.com\/es\/portfolio\/aashna-arjun\/","og_locale":"es_ES","og_type":"article","og_title":"Aashna &amp; Arjun - Kettiricordi | Aesthetic Documentary Wedding Photography","og_description":"Wedding in Girona, Spain","og_url":"https:\/\/kettiricordi.com\/es\/portfolio\/aashna-arjun\/","og_site_name":"Kettiricordi | Aesthetic Documentary Wedding Photography","article_modified_time":"2026-05-09T16:20:59+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/","url":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/","name":"Aashna &amp; Arjun - Kettiricordi | Aesthetic Documentary Wedding Photography","isPartOf":{"@id":"https:\/\/kettiricordi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/#primaryimage"},"image":{"@id":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/#primaryimage"},"thumbnailUrl":"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72.jpg","datePublished":"2024-05-20T19:13:29+00:00","dateModified":"2026-05-09T16:20:59+00:00","breadcrumb":{"@id":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/#primaryimage","url":"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72.jpg","contentUrl":"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/05\/AashnaArjun_72.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/kettiricordi.com\/portfolio\/aashna-arjun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kettiricordi.com\/"},{"@type":"ListItem","position":2,"name":"Aashna &amp; Arjun"}]},{"@type":"WebSite","@id":"https:\/\/kettiricordi.com\/#website","url":"https:\/\/kettiricordi.com\/","name":"Kettiricordi | Aesthetic Documentary Wedding Photography","description":"Wedding Photographer Barcelona","publisher":{"@id":"https:\/\/kettiricordi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kettiricordi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kettiricordi.com\/#organization","name":"Kettiricordi | Aesthetic Documentary Wedding Photography","url":"https:\/\/kettiricordi.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kettiricordi.com\/#\/schema\/logo\/image\/","url":"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/07\/KTR_Black.svg","contentUrl":"https:\/\/kettiricordi.com\/wp-content\/uploads\/2024\/07\/KTR_Black.svg","width":256,"height":142,"caption":"Kettiricordi | Aesthetic Documentary Wedding Photography"},"image":{"@id":"https:\/\/kettiricordi.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/portfolios\/11504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/portfolios"}],"about":[{"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/types\/portfolios"}],"replies":[{"embeddable":true,"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/comments?post=11504"}],"version-history":[{"count":44,"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/portfolios\/11504\/revisions"}],"predecessor-version":[{"id":17922,"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/portfolios\/11504\/revisions\/17922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/media\/10770"}],"wp:attachment":[{"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/media?parent=11504"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/kettiricordi.com\/es\/wp-json\/wp\/v2\/portfolio_cat?post=11504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}